{"id":58,"count":8,"description":"","link":"https:\/\/psychezwangerschap.nl\/en\/category\/cognitive-behavorial-therapy\/","name":"Cognitive Behavorial Therapy","slug":"cognitive-behavorial-therapy","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/psychezwangerschap.nl\/en\/wp-json\/wp\/v2\/categories\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/psychezwangerschap.nl\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/psychezwangerschap.nl\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/psychezwangerschap.nl\/en\/wp-json\/wp\/v2\/posts?categories=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}